{"id":4134,"count":1,"description":"","link":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/","name":"cassa\u00e7\u00e3o de mandato","slug":"cassacao-de-mandato","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/tag\\\/cassacao-de-mandato\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/tag\\\/cassacao-de-mandato\\\/\",\"name\":\"cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/tag\\\/cassacao-de-mandato\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/tag\\\/cassacao-de-mandato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cassa\u00e7\u00e3o de mandato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/","og_locale":"pt_BR","og_type":"article","og_title":"cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes","og_url":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/","og_site_name":"Marcelo Lopes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/","url":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/","name":"cassa\u00e7\u00e3o de mandato Archives | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/tag\/cassacao-de-mandato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"cassa\u00e7\u00e3o de mandato"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]}]}},"_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags\/4134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts?tags=4134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}