{"id":69526,"date":"2026-09-01T20:00:24","date_gmt":"2026-09-01T23:00:24","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/site\/?p=69526"},"modified":"2026-09-01T17:00:51","modified_gmt":"2026-09-01T20:00:51","slug":"muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/","title":{"rendered":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE"},"content":{"rendered":"<p>Muria\u00e9 aparece na segunda posi\u00e7\u00e3o como munic\u00edpio mais populoso da Zona da Mata, com 108.716 habitantes na estimativa populacional divulgada pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) em 28 de agosto de 2026. Est\u00e1 atr\u00e1s apenas de Juiz de Fora e pouco \u00e0 frente de Ub\u00e1.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8\u00a0<span style=\"color: #008000;\">Siga o Site do Marcelo Lopes no<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong>Facebook<\/strong><\/a><\/span>\u00a0<span style=\"color: #008000;\">e no<\/span>\u00a0<span style=\"color: #800000;\"><strong><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/strong><\/span><\/span><\/h4>\n<h4 class=\"p1\">\ud83d\udcf1<span style=\"color: #008000;\">Participe do grupo de<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong>WhatsApp<\/strong><\/a><\/span> <span style=\"color: #008000;\">do Site do Marcelo Lopes<\/span><\/h4>\n<p>Aqui na regi\u00e3o, os n\u00fameros divulgados colocam Juiz de Fora na primeira posi\u00e7\u00e3o, com 569.588 habitantes. Muria\u00e9 aparece em seguida, com 108.716, enquanto Ub\u00e1 registra 107.613 moradores. Cataguases, conforme o levantamento, possui uma popula\u00e7\u00e3o de 67.600 habitantes, 132 a menos do que em 2025 (67.732).<\/p>\n<p>Em compara\u00e7\u00e3o com a estimativa populacional de 2025, Muria\u00e9 registrou aumento de 269 habitantes. Os dados fazem parte do levantamento realizado pelo IBGE para estabelecer a popula\u00e7\u00e3o total dos estados e munic\u00edpios brasileiros.<\/p>\n<p>A estimativa considera uma contagem realizada at\u00e9 1\u00ba de julho de 2026. O levantamento tamb\u00e9m apresenta os dados referentes \u00e0 popula\u00e7\u00e3o do pa\u00eds.<\/p>\n<p>Segundo o IBGE, a popula\u00e7\u00e3o brasileira est\u00e1 estimada em 214,2 milh\u00f5es de pessoas em 2026. O n\u00famero representa crescimento de 0,37% em rela\u00e7\u00e3o \u00e0 estimativa de 2025.<\/p>\n<p>Entre os munic\u00edpios brasileiros, S\u00e3o Paulo, capital, continua sendo o mais populoso, com 11,9 milh\u00f5es de habitantes. Na outra ponta est\u00e1 Serra da Saudade, em Minas Gerais, o munic\u00edpio menos populoso do Brasil. A cidade possui 857 habitantes na estimativa de 2026.<\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/cataguases-tem-menos-moradores-do-que-em-2010-diz-censo-do-ibge\/\"><strong><span style=\"color: #800000;\">Cataguases tem menos moradores do que em 2010, diz Censo do IBGE<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/29\/dez-cidades-da-regiao-tambem-encolheram-segundo-o-censo-2022\/\"><strong><span style=\"color: #800000;\">Dez cidades da regi\u00e3o tamb\u00e9m &#8220;encolheram&#8221; segundo o Censo 2022<\/span><\/strong><\/a><\/p>\n<p>Informa\u00e7\u00f5es e foto: R\u00e1dio Muria\u00e9<\/p>\n<div class=\"dvuhj6a97be754a5a8\" ><div style=\"margin-left: auto; margin-right: auto; text-align: center; margin-top: 50px; \" id=\"teste-222571303\"><a href=\"https:\/\/marcelolopes.jor.br\/site\/edital-audiencia-publica-energisa-minas-rio-2026\/\" aria-label=\"banneredital\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png\" alt=\"\"  srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png 812w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-300x56.png 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-768x144.png 768w\" sizes=\"(max-width: 812px) 100vw, 812px\" width=\"812\" height=\"152\"  style=\"display: inline-block;\" \/><\/a><\/div><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.dvuhj6a97be754a5a8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dvuhj6a97be754a5a8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dvuhj6a97be754a5a8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dvuhj6a97be754a5a8 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dvuhj6a97be754a5a8 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"kdunm6a97be7550e05\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.kdunm6a97be7550e05 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kdunm6a97be7550e05 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kdunm6a97be7550e05 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kdunm6a97be7550e05 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kdunm6a97be7550e05 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Muria\u00e9 aparece na segunda posi\u00e7\u00e3o como munic\u00edpio mais populoso da Zona da Mata, com 108.716 habitantes na estimativa populacional divulgada pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) em 28 de agosto de 2026. Est\u00e1 atr\u00e1s apenas de Juiz de<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/\">Leia mais <span class=\"screen-reader-text\">Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":69529,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes<\/title>\n<meta name=\"description\" content=\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes\" \/>\n<meta property=\"og:description\" content=\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T23:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE\",\"datePublished\":\"2026-09-01T23:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/1-46.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/\",\"name\":\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/1-46.jpeg\",\"datePublished\":\"2026-09-01T23:00:24+00:00\",\"description\":\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/1-46.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/1-46.jpeg\",\"width\":750,\"height\":500,\"caption\":\"Muria\u00e9 ultrapassa Ub\u00e1 em\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/09\\\/01\\\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"width\":328,\"height\":96,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes","description":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/","og_locale":"pt_BR","og_type":"article","og_title":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes","og_description":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2026-09-01T23:00:24+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE","datePublished":"2026-09-01T23:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/","url":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/","name":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg","datePublished":"2026-09-01T23:00:24+00:00","description":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE. Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/1-46.jpeg","width":750,"height":500,"caption":"Muria\u00e9 ultrapassa Ub\u00e1 em"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/09\/01\/muriae-ultrapassa-uba-em-numero-de-habitantes-diz-ibge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Muria\u00e9 ultrapassa Ub\u00e1 em n\u00famero de habitantes, diz IBGE"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","width":328,"height":96,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Cataguases reduziu sua popula\u00e7\u00e3o em 132 habitantes, segundo o IBGE.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/69526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=69526"}],"version-history":[{"count":3,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/69526\/revisions"}],"predecessor-version":[{"id":69530,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/69526\/revisions\/69530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/69529"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=69526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=69526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=69526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}