{"id":66875,"date":"2026-06-25T12:00:45","date_gmt":"2026-06-25T15:00:45","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/site\/?p=66875"},"modified":"2026-06-25T09:43:51","modified_gmt":"2026-06-25T12:43:51","slug":"sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/","title":{"rendered":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco"},"content":{"rendered":"<p>As quatro pessoas mortas na s\u00e9rie de ataques a facadas ocorrida na ter\u00e7a (23) em Visconde do Rio Branco, foram sepultadas nesta quarta-feira, 24 de junho. Os crimes ocorreram em diferentes bairros da cidade. O agressor foi identificado como Igor Moreira, de 31 anos. Ele morreu ap\u00f3s ser baleado e contido pela Pol\u00edcia Militar (PM).<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8\u00a0<span style=\"color: #008000;\">Siga o Site do Marcelo Lopes no<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong>Facebook<\/strong><\/a><\/span>\u00a0<span style=\"color: #008000;\">e no<\/span>\u00a0<span style=\"color: #800000;\"><strong><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/strong><\/span><\/span><\/h4>\n<h4 class=\"p1\">\ud83d\udcf1<span style=\"color: #008000;\">Participe do grupo de<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong>WhatsApp<\/strong><\/a><\/span> <span style=\"color: #008000;\">do Site do Marcelo Lopes<\/span><\/h4>\n<p>Sidnei de Jesus Silva, Alexandre Jos\u00e9 Ribeiro e S\u00e9rgio Adriane dos Santos foram enterrados em Visconde do Rio Branco, cidade onde o crime ocorreu, enquanto Thais Ramos Gon\u00e7alves foi sepultada no distrito de Monte Celeste, em S\u00e3o Geraldo, munic\u00edpio vizinho. (foto montagem abaixo).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-66849\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/mortos.jpg-300x157.avif\" alt=\"\" width=\"700\" height=\"365\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/mortos.jpg-300x157.avif 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/mortos.jpg-768x401.avif 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/mortos.jpg.avif 1000w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>As identidades das v\u00edtimas foram confirmadas ao g1 pela Funer\u00e1ria Rio Branco. Veja quem eram:<\/p>\n<p>\u25aa\ufe0f<strong>Thais Ramos Gon\u00e7alves<\/strong>, de 31 anos: professora da rede p\u00fablica, companheira do agressor e m\u00e3e de uma menina. A primeira a ser morta.<\/p>\n<p>\u25aa\ufe0f<strong>Sidnei de Jesus Silva<\/strong>, de 31 anos: trabalhava com servi\u00e7os gerais, casado e pai de uma menina. N\u00e3o se sabe tinha rela\u00e7\u00e3o com o agressor. Foi o segundo a ser morto.<\/p>\n<p>\u25aa\ufe0f<strong>Alexandre Jos\u00e9 Ribeiro<\/strong>, de 45 anos: N\u00e3o tinha rela\u00e7\u00e3o com o agressor. Foi o terceiro a ser morto.<\/p>\n<p>\u25aa\ufe0f<strong>S\u00e9rgio Adriane dos Santos<\/strong>, de 55 anos: lavador de carro. N\u00e3o tinha rela\u00e7\u00e3o com o agressor. Foi o quarto a ser morto.<\/p>\n<p>At\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, n\u00e3o havia informa\u00e7\u00f5es sobre o vel\u00f3rio ou o sepultamento de Igor Moreira.<\/p>\n<h3>Entenda o caso<\/h3>\n<p>O rastro de viol\u00eancia come\u00e7ou por volta das 14h40 de ter\u00e7a-feira, quando Igor Moreira matou a companheira, Thais Ramos, dentro de casa.<\/p>\n<p>Ap\u00f3s o feminic\u00eddio, ele saiu \u00e0s ruas em uma motocicleta e atacou outras quatro pessoas aleatoriamente.<\/p>\n<p>Al\u00e9m dos quatro mortos, um homem de 34 anos sobreviveu ao ataque. Ele teve ferimentos leves e permanecia internado no Hospital S\u00e3o Jo\u00e3o Batista at\u00e9 as 18h desta ter\u00e7a.<\/p>\n<p>A Pol\u00edcia Civil investiga a motiva\u00e7\u00e3o do crime. As principais linhas de investiga\u00e7\u00e3o indicam que o autor pode ter sofrido um surto psic\u00f3tico ou estaria sob efeito de entorpecentes no momento das agress\u00f5es.<\/p>\n<p>O registro policial foi feito como feminic\u00eddio consumado, seguido de homic\u00eddios e uma tentativa de homic\u00eddio.<\/p>\n<p>A prefeitura de Visconde do Rio Branco decretou luto oficial no munic\u00edpio.<\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/24\/veja-a-cronologia-da-tragedia-que-abalou-visconde-do-rio-branco\/\"><strong><span style=\"color: #800000;\">Veja a cronologia da trag\u00e9dia que abalou Visconde do Rio Branco<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/23\/homem-mata-quatro-pessoas-a-facadas-em-visconde-do-rio-branco\/\"><strong><span style=\"color: #800000;\">Homem mata quatro pessoas a facadas em Visconde do Rio Branco<\/span><\/strong><\/a><\/p>\n<p>Fonte e fotos: g1 Zona da Mata<\/p>\n<div class=\"htvjb6a97f68e81a2c\" ><div style=\"margin-left: auto; margin-right: auto; text-align: center; margin-top: 50px; \" id=\"teste-867294376\"><a href=\"https:\/\/marcelolopes.jor.br\/site\/edital-audiencia-publica-energisa-minas-rio-2026\/\" aria-label=\"banneredital\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png\" alt=\"\"  srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png 812w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-300x56.png 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-768x144.png 768w\" sizes=\"(max-width: 812px) 100vw, 812px\" width=\"812\" height=\"152\"  style=\"display: inline-block;\" \/><\/a><\/div><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.htvjb6a97f68e81a2c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.htvjb6a97f68e81a2c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.htvjb6a97f68e81a2c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.htvjb6a97f68e81a2c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.htvjb6a97f68e81a2c {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"djdap6a97f68e877eb\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.djdap6a97f68e877eb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.djdap6a97f68e877eb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.djdap6a97f68e877eb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.djdap6a97f68e877eb {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.djdap6a97f68e877eb {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>As quatro pessoas mortas na s\u00e9rie de ataques a facadas ocorrida na ter\u00e7a (23) em Visconde do Rio Branco, foram sepultadas nesta quarta-feira, 24 de junho. Os crimes ocorreram em diferentes bairros da cidade. O agressor foi identificado como Igor<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/\">Leia mais <span class=\"screen-reader-text\">Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":66877,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio<\/title>\n<meta name=\"description\" content=\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio\" \/>\n<meta property=\"og:description\" content=\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T15:00:45+00:00\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco\",\"datePublished\":\"2026-06-25T15:00:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/sepultamento-visconde.jpg.jpeg.avif\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/\",\"name\":\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/sepultamento-visconde.jpg.jpeg.avif\",\"datePublished\":\"2026-06-25T15:00:45+00:00\",\"description\":\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/sepultamento-visconde.jpg.jpeg.avif\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/sepultamento-visconde.jpg.jpeg.avif\",\"width\":1000,\"height\":674,\"caption\":\"Sepultadas as v\u00edtimas de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2026\\\/06\\\/25\\\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"width\":328,\"height\":96,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio","description":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/","og_locale":"pt_BR","og_type":"article","og_title":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio","og_description":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o","og_url":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2026-06-25T15:00:45+00:00","author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco","datePublished":"2026-06-25T15:00:45+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/sepultamento-visconde.jpg.jpeg.avif","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/","url":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/","name":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/sepultamento-visconde.jpg.jpeg.avif","datePublished":"2026-06-25T15:00:45+00:00","description":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco. Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/sepultamento-visconde.jpg.jpeg.avif","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/06\/sepultamento-visconde.jpg.jpeg.avif","width":1000,"height":674,"caption":"Sepultadas as v\u00edtimas de"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2026\/06\/25\/sepultadas-as-vitimas-de-ataques-em-serie-em-visconde-do-rio-branco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Sepultadas as v\u00edtimas de ataques em s\u00e9rie em Visconde do Rio Branco"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","width":328,"height":96,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Informa\u00e7\u00f5es sobre o sepultamento de Igor Moreira, autor dos crimes, n\u00e3o foram divulgadas.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/66875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=66875"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/66875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/66877"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=66875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=66875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=66875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}