{"id":52467,"date":"2024-10-02T20:00:03","date_gmt":"2024-10-02T23:00:03","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=52467"},"modified":"2024-10-02T19:08:58","modified_gmt":"2024-10-02T22:08:58","slug":"certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/","title":{"rendered":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo"},"content":{"rendered":"<p>A emiss\u00e3o de novos modelos de certid\u00f5es de nascimento, casamento e \u00f3bito passar\u00e1 a ser obrigat\u00f3ria em todos os cart\u00f3rios de registro civil do Pa\u00eds a partir de 1\u00ba de janeiro de 2025.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8\u00a0<span style=\"color: #808080;\">Siga o Site do Marcelo Lopes no<\/span>\u00a0<a style=\"transition-property: all;\" href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a>\u00a0<span style=\"color: #808080;\">e no<\/span>\u00a0<strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span style=\"font-size: 1.5rem;\">\ud83d\udcf1<\/span><span style=\"color: #808080;\">Receba no<\/span><span style=\"font-size: 1.5rem;\">\u00a0<\/span><a style=\"font-size: 1.5rem;\" href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a><span style=\"font-size: 1.5rem;\">\u00a0<\/span><span style=\"color: #808080;\">as not\u00edcias do Site do Marcelo Lope<\/span><span style=\"color: #808080; font-size: 1.5rem;\">s<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Um provimento da Corregedoria Nacional de Justi\u00e7a, vinculada ao Conselho Nacional de Justi\u00e7a (CNJ), determina a inclus\u00e3o de novas informa\u00e7\u00f5es nos documentos e, na confec\u00e7\u00e3o deles, o uso de um papel especial que ajuda a evitar documentos falsos.<\/p>\n<p>O novo modelo de certid\u00e3o de nascimento, por exemplo, passa a ter dois campos bem definidos: um para o local do nascimento e outro para seu domic\u00edlio.<\/p>\n<p>No caso da certid\u00e3o de casamento, a principal mudan\u00e7a foi uma distin\u00e7\u00e3o entre a data da celebra\u00e7\u00e3o e a data do registro, o que n\u00e3o vinha sendo contemplado.<\/p>\n<p>J\u00e1 a certid\u00e3o de \u00f3bito n\u00e3o previa a data da morte, s\u00f3 a data em que foi registrada. Agora, o documento passa a conter as duas datas em campos distintos, para esclarecer eventuais consequ\u00eancias jur\u00eddicas.<\/p>\n<p>&#8220;Esses documentos s\u00e3o fundamentais para a vida civil e a atualiza\u00e7\u00e3o \u00e9 uma resposta \u00e0s transforma\u00e7\u00f5es que observamos ao longo dos anos&#8221;, diz a ju\u00edza auxiliar da Corregedoria, Liz Rezende de Andrade.<\/p>\n<p>A iniciativa para a mudan\u00e7a surgiu de um pedido de um registrador civil de Minas Gerais e foi amplamente discutida com a Associa\u00e7\u00e3o dos Registradores de Pessoas Naturais do Brasil (Arpen Brasil), levando a corregedoria nacional a determinar novas regras.<\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2020\/11\/19\/hospital-de-cataguases-inaugura-posto-do-cartorio-de-registro-civil\/\"><strong><span style=\"color: #800000;\">Hospital de Cataguases inaugura posto do cart\u00f3rio de registro civil<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2024\/02\/28\/veja-como-fica-o-registro-de-quem-nasce-no-dia-29-de-fevereiro\/\"><strong><span style=\"color: #800000;\">Veja como fica o registro de quem nasce no dia 29 de fevereiro<\/span><\/strong><\/a><\/p>\n<p>Fonte: Veja e Tribuna de Minas | Foto: Reprodu\u00e7\u00e3o<\/p>\n<div class=\"hdrir6a97f638471dc\" ><div style=\"margin-left: auto; margin-right: auto; text-align: center; margin-top: 50px; \" id=\"teste-379582866\"><a href=\"https:\/\/marcelolopes.jor.br\/site\/edital-audiencia-publica-energisa-minas-rio-2026\/\" aria-label=\"banneredital\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png\" alt=\"\"  srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png 812w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-300x56.png 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-768x144.png 768w\" sizes=\"(max-width: 812px) 100vw, 812px\" width=\"812\" height=\"152\"  style=\"display: inline-block;\" \/><\/a><\/div><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.hdrir6a97f638471dc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.hdrir6a97f638471dc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.hdrir6a97f638471dc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.hdrir6a97f638471dc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.hdrir6a97f638471dc {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"fjqcv6a97f6384d628\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.fjqcv6a97f6384d628 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fjqcv6a97f6384d628 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fjqcv6a97f6384d628 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fjqcv6a97f6384d628 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fjqcv6a97f6384d628 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>A emiss\u00e3o de novos modelos de certid\u00f5es de nascimento, casamento e \u00f3bito passar\u00e1 a ser obrigat\u00f3ria em todos os cart\u00f3rios de registro civil do Pa\u00eds a partir de 1\u00ba de janeiro de 2025.<\/p>\n","protected":false},"author":2,"featured_media":52470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo<\/title>\n<meta name=\"description\" content=\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo\" \/>\n<meta property=\"og:description\" content=\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T23:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo\",\"datePublished\":\"2024-10-02T23:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certidoes1.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/\",\"name\":\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certidoes1.jpg\",\"datePublished\":\"2024-10-02T23:00:03+00:00\",\"description\":\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certidoes1.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/certidoes1.jpg\",\"width\":800,\"height\":499,\"caption\":\"Certid\u00f5es de nascimento, casamento\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/10\\\/02\\\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"width\":328,\"height\":96,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo","description":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/","og_locale":"pt_BR","og_type":"article","og_title":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo","og_description":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-10-02T23:00:03+00:00","og_image":[{"width":800,"height":499,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo","datePublished":"2024-10-02T23:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/","name":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg","datePublished":"2024-10-02T23:00:03+00:00","description":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo. Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/10\/certidoes1.jpg","width":800,"height":499,"caption":"Certid\u00f5es de nascimento, casamento"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/10\/02\/certidoes-de-nascimento-casamento-e-obito-terao-novo-modelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Certid\u00f5es de nascimento, casamento e \u00f3bito ter\u00e3o novo modelo"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","width":328,"height":96,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Medida ser\u00e1 obrigat\u00f3ria em cart\u00f3rios de registro civil em 2025.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=52467"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/52470"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=52467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=52467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=52467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}