{"id":52254,"date":"2024-09-24T16:00:09","date_gmt":"2024-09-24T19:00:09","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=52254"},"modified":"2024-09-24T15:29:22","modified_gmt":"2024-09-24T18:29:22","slug":"energisa-realiza-simulado-de-seu-plano-de-contingencia","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/","title":{"rendered":"Energisa realiza simulado de seu Plano de Conting\u00eancia"},"content":{"rendered":"<p>Imagine a seguinte cena: Final de um dia qualquer de trabalho e, de repente, come\u00e7a a cair uma tempestade sobre Cataguases acompanhada de uma forte ventania. Chove granizo por alguns minutos. O vento sacode as janelas e as ruas come\u00e7am a ficar alagadas, galhos de \u00e1rvores caem interditando ruas, raios e trov\u00f5es se repetem. A situa\u00e7\u00e3o se agrava ainda mais porque, em um determinado ponto da cidade, a chuva provocou mais estragos comprometendo o fornecimento de energia el\u00e9trica. Est\u00e1 escurecendo e a cidade est\u00e1 \u00e0s escuras.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8 <span style=\"color: #808080;\">Siga o Site do Marcelo Lopes no<\/span> <a href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a> <span style=\"color: #808080;\">e no<\/span> <strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf1<span style=\"color: #808080;\">Receba no<\/span> <a href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a> <span style=\"color: #808080;\">as not\u00edcias do Site do Marcelo Lopes<\/span><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52261\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande-1024x576.jpeg\" alt=\"Energisa realiza simulado de\" width=\"700\" height=\"394\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande-1024x576.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande-300x169.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande-768x432.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande-1200x675.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7812-Grande.jpeg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>Uma situa\u00e7\u00e3o como esta \u00e9 mais comum do que se imagina neste per\u00edodo de chuvas que est\u00e1 come\u00e7ando no pa\u00eds. Evitar temporais n\u00e3o \u00e9 poss\u00edvel, mas \u00e9 perfeitamente vi\u00e1vel minimizar os efeitos desta adversidade clim\u00e1tica. \u00c9 por isso que a Energisa Minas Rio implementou h\u00e1 v\u00e1rios anos um Plano de Conting\u00eancia e vem minimizando com profissionalismo e efici\u00eancia os efeitos das fortes chuvas e as adversidades clim\u00e1ticas desta \u00e9poca do ano. Nesta ter\u00e7a-feira, 24 de setembro, foi dia de treinar a execu\u00e7\u00e3o desse Plano de Conting\u00eancia preparando suas equipes t\u00e9cnicas para o atendimento nestes momentos de crise.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-52258\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7793-Grande-576x1024.jpeg\" alt=\"Energisa realiza simulado de\" width=\"200\" height=\"356\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7793-Grande-576x1024.jpeg 576w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7793-Grande-169x300.jpeg 169w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7793-Grande-675x1200.jpeg 675w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7793-Grande.jpeg 720w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Dezenas de funcion\u00e1rios, diretoria e at\u00e9 a Defesa Civil e o Corpo de Bombeiros participaram desta simula\u00e7\u00e3o que come\u00e7ou \u00e0s 7h, na sede da empresa na Reta da Saudade, em Cataguases. Conforme explicou Victor Rispoli, gerente de Opera\u00e7\u00e3o da Energisa Minas Rio, antes das equipes sa\u00edrem a campo (veja o v\u00eddeo ao final do texto), &#8220;o objetivo desse treinamento \u00e9 buscar &#8211; em situa\u00e7\u00e3o de emerg\u00eancia &#8211; restabelecer o fornecimento de energia o mais depressa poss\u00edvel para os clientes. Para ter essa efici\u00eancia \u00e9 que realizamos hoje este simulado de conting\u00eancia para mostrar nosso poder de mobiliza\u00e7\u00e3o e toda a estrutura para atuar neste momento de crise. Ainda contamos com o apoio da Defesa Civil e Corpo de Bombeiros, para que possamos trabalhar de forma mais eficaz e com seguran\u00e7a&#8221;, destacou.<\/p>\n<p>Eduardo Mantovani, presidente da Energisa Minas Rio e Rodolfo Acialdi Pinheiro, Diretor T\u00e9cnico e Comercial da empresa, participaram da abertura do simulado em que destacaram a import\u00e2ncia do Plano de Conting\u00eancia da empresa, al\u00e9m do treinamento para que tudo funcione como o planejado nos momentos de crise. Vale lembrar que nas cidades da \u00e1rea de concess\u00e3o da Energisa Minas Rio foram registrados ano passado, mais de 550 mil raios, que vieram acompanhados de chuvas t\u00edpicas de ver\u00e3o e rajadas de vento. &#8220;Contar com equipes experientes e capacitadas para garantir o restabelecimento do fornecimento de energia com rapidez, seguran\u00e7a e efici\u00eancia, \u00e9 essencial nestes momentos&#8221;, assegurou Mantovani.<\/p>\n<p>Veja o v\u00eddeo clicando <a href=\"https:\/\/youtu.be\/SxOjBF1meFE\"><span style=\"color: #800000;\"><strong>neste link<\/strong><\/span><\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52260\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande-1024x576.jpeg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande-1024x576.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande-300x169.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande-768x432.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande-1200x675.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7802-Grande.jpeg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52259\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande-1024x576.jpeg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande-1024x576.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande-300x169.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande-768x432.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande-1200x675.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7799-Grande.jpeg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2023\/09\/13\/energisa-treina-equipes-em-preparacao-para-o-periodo-de-chuvas\/\"><strong><span style=\"color: #800000;\">Energisa treina equipes em prepara\u00e7\u00e3o para o per\u00edodo de chuvas<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2022\/10\/19\/energisa-realiza-seminario-sobre-o-periodo-de-chuvas\/\"><strong><span style=\"color: #800000;\">Energisa realiza semin\u00e1rio sobre o per\u00edodo de chuvas<\/span><\/strong><\/a><\/p>\n<div class=\"vnlxk6a0438a806e79\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.vnlxk6a0438a806e79 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vnlxk6a0438a806e79 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vnlxk6a0438a806e79 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vnlxk6a0438a806e79 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vnlxk6a0438a806e79 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"rnjtr6a0438a80cc27\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.rnjtr6a0438a80cc27 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rnjtr6a0438a80cc27 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rnjtr6a0438a80cc27 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rnjtr6a0438a80cc27 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rnjtr6a0438a80cc27 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Imagine a seguinte cena: Final de um dia qualquer de trabalho e, de repente, come\u00e7a a cair uma tempestade sobre Cataguases acompanhada de uma forte ventania. Chove granizo por alguns minutos. O vento sacode as janelas e as ruas come\u00e7am<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/\">Leia mais <span class=\"screen-reader-text\">Energisa realiza simulado de seu Plano de Conting\u00eancia<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":52262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes<\/title>\n<meta name=\"description\" content=\"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes\" \/>\n<meta property=\"og:description\" content=\"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T19:00:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Energisa realiza simulado de seu Plano de Conting\u00eancia\",\"datePublished\":\"2024-09-24T19:00:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7818-Grande.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/\",\"name\":\"Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7818-Grande.jpeg\",\"datePublished\":\"2024-09-24T19:00:09+00:00\",\"description\":\"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7818-Grande.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7818-Grande.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Energisa realiza simulado de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/24\\\/energisa-realiza-simulado-de-seu-plano-de-contingencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energisa realiza simulado de seu Plano de Conting\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes","description":"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes","og_description":"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-09-24T19:00:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Energisa realiza simulado de seu Plano de Conting\u00eancia","datePublished":"2024-09-24T19:00:09+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/","name":"Energisa realiza simulado de seu Plano de Conting\u00eancia | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg","datePublished":"2024-09-24T19:00:09+00:00","description":"Energisa realiza simulado de seu Plano de Contingencia. Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/IMG_7818-Grande.jpeg","width":1280,"height":720,"caption":"Energisa realiza simulado de"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/24\/energisa-realiza-simulado-de-seu-plano-de-contingencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Energisa realiza simulado de seu Plano de Conting\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Objetivo \u00e9 oferecer atendimento eficiente em momentos de adversidade clim\u00e1tica.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=52254"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/52262"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=52254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=52254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=52254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}