{"id":52228,"date":"2024-09-23T16:00:06","date_gmt":"2024-09-23T19:00:06","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=52228"},"modified":"2024-09-23T10:47:38","modified_gmt":"2024-09-23T13:47:38","slug":"adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/","title":{"rendered":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha"},"content":{"rendered":"<p>Uma adolescente foi apreendida pela Pol\u00edcia Militar Rodovi\u00e1ria, na noite deste domingo, 22 de setembro, em Rio Pomba (67 km de Cataguases), com duas barras de maconha.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8 <span style=\"color: #808080;\">Siga o Site do Marcelo Lopes no<\/span> <a href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a> <span style=\"color: #808080;\">e no<\/span> <strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf1<span style=\"color: #808080;\">Receba no<\/span> <a href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a> <span style=\"color: #808080;\">as not\u00edcias do Site do Marcelo Lopes<\/span><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Ela, que \u00e9 natural de Juiz de Fora, viajava em um \u00f4nibus que fazia a linha Rio de Janeiro\/Vi\u00e7osa. O ve\u00edculo foi parado em uma blitz da PMRv que acontecia na rodovia MGC-265, munic\u00edpio de Rio Pomba, como parte da opera\u00e7\u00e3o Sentinela da Estrada.<\/p>\n<p>A adolescente, de 16 anos, demonstrou nervosismo ao ser entrevistada pelos policiais e teve sua bagagem revistada, quando foram encontradas duas barras de maconha. Ela foi apreendida por ato infracional an\u00e1logo ao tr\u00e1fico de drogas e foi acompanhada pelo Conselho Tutelar durante todo o processo.<\/p>\n<p>Durante a abordagem junto a adolescente, os militares descobriram atrav\u00e9s do sistema informatizado, que ela era dada como desaparecida. Conforme o Boletim de Ocorr\u00eancia de seu desaparecimento, ela teria fugido da Casa de Acolhimento Colmeia, em Juiz de Fora, no dia 9 de dezembro de 2023.<\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2024\/07\/04\/pf-cumpre-mandados-em-rio-pomba-contra-golpes-do-falso-emprestimo\/\"><strong><span style=\"color: #800000;\">PF cumpre mandados em Rio Pomba contra golpes do falso empr\u00e9stimo<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2024\/06\/15\/idosa-cai-em-golpe-financeiro-em-rio-pomba\/\"><strong><span style=\"color: #800000;\">Idosa cai em golpe financeiro em Rio Pomba<\/span><\/strong><\/a><\/p>\n<p>Fonte e foto: PMRv-divulga\u00e7\u00e3o<\/p>\n<div class=\"gdocr6a03efb529f40\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.gdocr6a03efb529f40 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gdocr6a03efb529f40 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gdocr6a03efb529f40 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gdocr6a03efb529f40 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gdocr6a03efb529f40 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"ovtse6a03efb530367\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.ovtse6a03efb530367 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.ovtse6a03efb530367 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.ovtse6a03efb530367 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.ovtse6a03efb530367 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.ovtse6a03efb530367 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Uma adolescente foi apreendida pela Pol\u00edcia Militar Rodovi\u00e1ria, na noite deste domingo, 22 de setembro, em Rio Pomba (67 km de Cataguases), com duas barras de maconha.<\/p>\n","protected":false},"author":2,"featured_media":52232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adolescente que estava desaparecida \u00e9 apreendida com 2 barras<\/title>\n<meta name=\"description\" content=\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras\" \/>\n<meta property=\"og:description\" content=\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-23T19:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha\",\"datePublished\":\"2024-09-23T19:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/\"},\"wordCount\":227,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/maconha.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/\",\"name\":\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/maconha.jpg\",\"datePublished\":\"2024-09-23T19:00:06+00:00\",\"description\":\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/maconha.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/maconha.jpg\",\"width\":800,\"height\":550,\"caption\":\"Adolescente que estava desaparecida\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/23\\\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras","description":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/","og_locale":"pt_BR","og_type":"article","og_title":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras","og_description":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-09-23T19:00:06+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha","datePublished":"2024-09-23T19:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/"},"wordCount":227,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/","name":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg","datePublished":"2024-09-23T19:00:06+00:00","description":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha. Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/maconha.jpg","width":800,"height":550,"caption":"Adolescente que estava desaparecida"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/23\/adolescente-que-estava-desaparecida-e-apreendida-com-2-barras-de-maconha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Adolescente que estava desaparecida \u00e9 apreendida com 2 barras de maconha"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Ela estava em um \u00f4nibus interestadual que passava por Rio Pomba.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=52228"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/52232"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=52228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=52228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=52228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}