{"id":52173,"date":"2024-09-20T08:18:01","date_gmt":"2024-09-20T11:18:01","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=52173"},"modified":"2025-01-15T18:16:25","modified_gmt":"2025-01-15T21:16:25","slug":"tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/","title":{"rendered":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o"},"content":{"rendered":"<p class=\"p1\"><span style=\"font-size: 1rem; -webkit-text-size-adjust: 100%;\">O vereador cataguasense, Ricardo Dias (PV), segue impedido de ser candidato nestas elei\u00e7\u00f5es de 2024. Considerado ineleg\u00edvel em processo eleitoral julgado pelo juiz da 79\u00aa Zona Eleitoral de Cataguases, ele recorreu da decis\u00e3o junto ao TRE-MG &#8211; Tribunal Regional Eleitoral &#8211; onde tamb\u00e9m sofreu nova derrota.<\/span><br \/>\n<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8\u00a0<span style=\"color: #666699;\">Siga o Site do Marcelo Lopes no<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong>Facebook<\/strong><\/a><\/span>\u00a0<span style=\"color: #666699;\">e no<\/span>\u00a0<span style=\"color: #800000;\"><strong><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/strong><\/span><\/span><\/h4>\n<h4 class=\"p1\">\ud83d\udcf1<span style=\"color: #666699;\">Receba no<\/span>\u00a0<span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong>WhatsApp<\/strong><\/a><\/span>\u00a0<span style=\"color: #666699;\">as not\u00edcias do Site do Marcelo Lopes<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p class=\"p3\"><span class=\"s2\">Em decis\u00e3o monocr\u00e1tica, o desembargador Miguel Angelo de Alvarenga Lopes, manteve a decis\u00e3o de primeira inst\u00e2ncia, negando o recurso do atual vereador que tenta se lan\u00e7ar novamente candidato. Conforme aquele magistrado lembrou que Ricardo Dias \u201cfoi condenado, em decis\u00e3o colegiada proferida pelo Superior Tribunal de Justi\u00e7a, pela pr\u00e1tica do crime de tr\u00e1fico de drogas, crime este previsto no art. 1\u00ba da LC n. 64\/1990, a uma pena de 02 (dois) anos e 6 (seis) meses de reclus\u00e3o e 250 (duzentos e cinquenta) dias-multa, atraindo, assim, a aplica\u00e7\u00e3o do instituto da inelegibilidade.\u201d<\/span><\/p>\n<p class=\"p3\"><span class=\"s2\">Em seguida, Miguel Angelo afirmou que \u201co crime de tr\u00e1fico de drogas pelo qual o recorrente foi condenado n\u00e3o \u00e9 de menor potencial ofensivo e nem culposo.\u201d Ele finalizou sua decis\u00e3o negando tamb\u00e9m outro pedido de Ricardo Dias, para suspender o processo. Conforme o entendimento daquele Desembargador \u201cn\u00e3o \u00e9 o caso, pois n\u00e3o h\u00e1 pendencia de outro julgamento que interfira no julgamento do registro de candidatura.\u201d<span class=\"Apple-converted-space\">\u00a0 <\/span>Ricardo Dias pode recorrer ao TSE.<\/span><\/p>\n<div class=\"asych6a03c9b6383ca\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.asych6a03c9b6383ca {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.asych6a03c9b6383ca {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.asych6a03c9b6383ca {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.asych6a03c9b6383ca {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.asych6a03c9b6383ca {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"yifxf6a03c9b63e9cc\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.yifxf6a03c9b63e9cc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.yifxf6a03c9b63e9cc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.yifxf6a03c9b63e9cc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.yifxf6a03c9b63e9cc {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.yifxf6a03c9b63e9cc {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>O vereador cataguasense, Ricardo Dias (PV), segue impedido de ser candidato nestas elei\u00e7\u00f5es de 2024. Considerado ineleg\u00edvel em processo eleitoral julgado pelo juiz da 79\u00aa Zona Eleitoral de Cataguases, ele recorreu da decis\u00e3o junto ao TRE-MG &#8211; Tribunal Regional Eleitoral<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/\">Leia mais <span class=\"screen-reader-text\">TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":51907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes<\/title>\n<meta name=\"description\" content=\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes\" \/>\n<meta property=\"og:description\" content=\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T11:18:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T21:16:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o\",\"datePublished\":\"2024-09-20T11:18:01+00:00\",\"dateModified\":\"2025-01-15T21:16:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ricardo3.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/\",\"name\":\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ricardo3.jpg\",\"datePublished\":\"2024-09-20T11:18:01+00:00\",\"dateModified\":\"2025-01-15T21:16:25+00:00\",\"description\":\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ricardo3.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ricardo3.jpg\",\"width\":800,\"height\":550,\"caption\":\"Justi\u00e7a Eleitoral indefere candidatura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/20\\\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes","description":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/","og_locale":"pt_BR","og_type":"article","og_title":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes","og_description":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-09-20T11:18:01+00:00","article_modified_time":"2025-01-15T21:16:25+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o","datePublished":"2024-09-20T11:18:01+00:00","dateModified":"2025-01-15T21:16:25+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/","name":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg","datePublished":"2024-09-20T11:18:01+00:00","dateModified":"2025-01-15T21:16:25+00:00","description":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o. Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/Ricardo3.jpg","width":800,"height":550,"caption":"Justi\u00e7a Eleitoral indefere candidatura"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/20\/tre-mg-mantem-ricardo-dias-impedido-de-disputar-eleicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"TRE-MG mant\u00e9m Ricardo Dias impedido de disputar elei\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Decis\u00e3o foi divulgada hoje. Ele ainda pode recorrer ao TSE.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=52173"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/51907"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=52173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=52173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=52173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}