{"id":52103,"date":"2024-09-17T20:00:58","date_gmt":"2024-09-17T23:00:58","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=52103"},"modified":"2024-09-17T17:24:34","modified_gmt":"2024-09-17T20:24:34","slug":"acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/","title":{"rendered":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9"},"content":{"rendered":"<p>Dois carros de passeio e uma caminhonete se envolveram em um engavetamento na BR-116, pr\u00f3ximo a entrada de Itamuri, distrito de Muria\u00e9, nesta ter\u00e7a-feira, 17 de setembro.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8 <span style=\"color: #808080;\">Siga o Site do Marcelo Lopes no<\/span> <a href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a> <span style=\"color: #808080;\">e no<\/span> <strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf1<span style=\"color: #808080;\">Receba no<\/span> <a href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a> <span style=\"color: #808080;\">as not\u00edcias do Site do Marcelo Lopes<\/span><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Segundo informa\u00e7\u00f5es preliminares divulgadas pela R\u00e1dio Muria\u00e9, um dos condutores que seguia sentido norte teria perdido o controle do carro vindo a bater na traseira do outro ve\u00edculo que colidiu com o barranco, j\u00e1 a caminhonete n\u00e3o conseguiu desviar e tamb\u00e9m ser envolveu no acidente.<\/p>\n<p>Tr\u00eas pessoas ficaram feridas, sendo que uma delas, a que estava no carro que perdeu o controle, ficou presa nas ferragens e precisou ser removida por uma equipe do Corpo de Bombeiros. Unidade do SAMU prestou socorro \u00e0s v\u00edtimas e as levou at\u00e9 o Hospital S\u00e3o Paulo. Funcion\u00e1rios da Eco-RioMinas, empresa que administra aquele trecho da rodovia, prestaram os primeiros atendimentos aos envolvidos.<\/p>\n<p>Uma garoa fina ca\u00eda sobre rodovia no momento do acidente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52106\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1-1024x683.jpeg\" alt=\"\" width=\"700\" height=\"467\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1-1024x683.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1-300x200.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1-768x512.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1-1200x800.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1536x1024-1.jpeg 1536w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52104\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1-1024x683.jpeg\" alt=\"\" width=\"700\" height=\"467\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1-1024x683.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1-300x200.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1-768x512.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1-1200x800.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.18.12-1-1536x1024-1.jpeg 1536w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><strong>OUTRAS NOT\u00cdCIAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2024\/07\/29\/acidente-entre-cavalo-e-motocicleta-deixa-dois-feridos-na-br-116-em-muriae\/\"><strong><span style=\"color: #800000;\">Acidente entre cavalo e motocicleta deixa dois feridos na BR-116 em Muria\u00e9<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2024\/07\/22\/capotamento-deixa-casal-ferido-na-br-116-proximo-a-miradouro\/\"><strong><span style=\"color: #800000;\">Capotamento deixa casal ferido na BR-116, pr\u00f3ximo a Miradouro<\/span><\/strong><\/a><\/p>\n<p>Fonte e fotos: R\u00e1dio Muria\u00e9<\/p>\n<div class=\"fkyyo6a04a8624f8ce\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.fkyyo6a04a8624f8ce {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.fkyyo6a04a8624f8ce {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.fkyyo6a04a8624f8ce {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.fkyyo6a04a8624f8ce {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.fkyyo6a04a8624f8ce {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"mqthq6a04a86255a46\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.mqthq6a04a86255a46 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.mqthq6a04a86255a46 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.mqthq6a04a86255a46 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.mqthq6a04a86255a46 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.mqthq6a04a86255a46 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Dois carros de passeio e uma caminhonete se envolveram em um engavetamento na BR-116, pr\u00f3ximo a entrada de Itamuri, distrito de Muria\u00e9, nesta ter\u00e7a-feira, 17 de setembro.<\/p>\n","protected":false},"author":2,"featured_media":52105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes<\/title>\n<meta name=\"description\" content=\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes\" \/>\n<meta property=\"og:description\" content=\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T23:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9\",\"datePublished\":\"2024-09-17T23:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/\"},\"wordCount\":221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/\",\"name\":\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg\",\"datePublished\":\"2024-09-17T23:00:58+00:00\",\"description\":\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/09\\\/17\\\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes","description":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/","og_locale":"pt_BR","og_type":"article","og_title":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes","og_description":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-09-17T23:00:58+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9","datePublished":"2024-09-17T23:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/"},"wordCount":221,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/","name":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9 | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg","datePublished":"2024-09-17T23:00:58+00:00","description":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9. Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/09\/WhatsApp-Image-2024-09-17-at-14.27.06-1-1-1536x1024-1.jpeg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/09\/17\/acidente-deixa-tres-feridos-na-br-116-proximo-a-muriae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Acidente deixa tr\u00eas feridos na BR-116, pr\u00f3ximo a Muria\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Uma das v\u00edtimas ficou presa \u00e0s ferragens e teve ajuda dos Bombeiros.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=52103"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/52103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/52105"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=52103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=52103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=52103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}