{"id":48423,"date":"2024-04-18T10:00:47","date_gmt":"2024-04-18T13:00:47","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=48423"},"modified":"2024-04-18T09:16:46","modified_gmt":"2024-04-18T12:16:46","slug":"corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/","title":{"rendered":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9"},"content":{"rendered":"<p>Foi encontrado nesta quarta-feira, 17 de abril, \u00e0s margens do Rio Gl\u00f3ria, na BR-356, pr\u00f3ximo a Pedra Santa Maria, em Muria\u00e9, o corpo de Heronildo de Paula, cuja idade n\u00e3o foi revelada.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8 Siga o Site do Marcelo Lopes no <a href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a> e no <strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf1Receba no <a href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a> as not\u00edcias do Site do Marcelo Lopes<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Ele estava desaparecido desde o dia 27 de mar\u00e7o. Seu carro chegou a ser encontrado pr\u00f3ximo a Penitenci\u00e1ria de Muria\u00e9. Segundo informa\u00e7\u00f5es, ele saiu de casa naquele mesmo dia, dizendo que iria fazer umas cobran\u00e7as de trabalho e n\u00e3o voltou mais.<\/p>\n<p>Desde o seu desaparecimento, dezenas de amigos e familiares publicaram nas redes sociais pedindo informa\u00e7\u00f5es sobre seu poss\u00edvel paradeiro.<\/p>\n<p>O corpo foi encontrado em estado de decomposi\u00e7\u00e3o, com sinais de viol\u00eancia. Dentro de um dos bolsos foi localizada a chave do carro, um aparelho celular e um cart\u00e3o de cr\u00e9dito.<\/p>\n<p>A Pol\u00edcia Militar, Per\u00edcia T\u00e9cnica e Pol\u00edcia Civil, que vai investigar o caso, estiveram no local e realizaram os primeiros levantamentos. O corpo foi levado para o Instituto M\u00e9dico Legal (IML).<\/p>\n<p><strong>NOT\u00cdCIAS RELACIONADAS<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2024\/01\/02\/corpo-de-homem-desaparecido-e-localizado-no-rio-muriae\/\"><strong><span style=\"color: #800000;\">Corpo de homem desaparecido \u00e9 localizado no Rio Muria\u00e9<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2023\/06\/07\/corpo-encontrado-no-fundo-de-rio-em-muriae-foi-vitima-de-emboscada\/\"><strong><span style=\"color: #800000;\">Corpo encontrado no fundo de rio em Muria\u00e9 foi v\u00edtima de emboscada<\/span><\/strong><\/a><\/p>\n<p>Fonte e foto: R\u00e1dio Muria\u00e9<\/p>\n<div class=\"behyu6a04cf950f0a7\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.behyu6a04cf950f0a7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.behyu6a04cf950f0a7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.behyu6a04cf950f0a7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.behyu6a04cf950f0a7 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.behyu6a04cf950f0a7 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vairo6a04cf95178d1\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.vairo6a04cf95178d1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vairo6a04cf95178d1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vairo6a04cf95178d1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vairo6a04cf95178d1 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vairo6a04cf95178d1 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Foi encontrado nesta quarta-feira, 17 de abril, \u00e0s margens do Rio Gl\u00f3ria, na BR-356, pr\u00f3ximo a Pedra Santa Maria, em Muria\u00e9, o corpo de Heronildo de Paula, cuja idade n\u00e3o foi revelada.<\/p>\n","protected":false},"author":2,"featured_media":48424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes<\/title>\n<meta name=\"description\" content=\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes\" \/>\n<meta property=\"og:description\" content=\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T13:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9\",\"datePublished\":\"2024-04-18T13:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-29-jpeg.webp\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/\",\"name\":\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-29-jpeg.webp\",\"datePublished\":\"2024-04-18T13:00:47+00:00\",\"description\":\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-29-jpeg.webp\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/01-29-jpeg.webp\",\"width\":750,\"height\":500,\"caption\":\"Corpo de homem \u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2024\\\/04\\\/18\\\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes","description":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/","og_locale":"pt_BR","og_type":"article","og_title":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes","og_description":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2024-04-18T13:00:47+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9","datePublished":"2024-04-18T13:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/","url":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/","name":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9 | Marcelo Lopes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp","datePublished":"2024-04-18T13:00:47+00:00","description":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9. Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/04\/01-29-jpeg.webp","width":750,"height":500,"caption":"Corpo de homem \u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2024\/04\/18\/corpo-de-homem-e-encontrado-as-margens-da-br-356-em-muriae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Corpo de homem \u00e9 encontrado \u00e0s margens da BR-356, em Muria\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Heronildo de Paula estava desaparecido desde o dia 27 de mar\u00e7o.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/48423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=48423"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/48423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/48424"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=48423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=48423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=48423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}