{"id":41852,"date":"2023-06-28T07:00:30","date_gmt":"2023-06-28T10:00:30","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=41852"},"modified":"2023-06-27T19:08:41","modified_gmt":"2023-06-27T22:08:41","slug":"ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/","title":{"rendered":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022"},"content":{"rendered":"<p>O <a href=\"http:\/\/www.ibge.gov.br\/\"><strong><span style=\"color: #800000;\">IBGE<\/span><\/strong><\/a> vai divulgar, \u00e0s 10 horas de hoje, 28 de junho, os Primeiros Resultados de Popula\u00e7\u00e3o e Domic\u00edlios do Censo Demogr\u00e1fico 2022, apresentando um conjunto de informa\u00e7\u00f5es b\u00e1sicas sobre os totais populacionais e de domic\u00edlios no Pa\u00eds em diferentes n\u00edveis geogr\u00e1ficos e recortes, al\u00e9m de diversos indicadores derivados dessas informa\u00e7\u00f5es, como a m\u00e9dia de moradores por domic\u00edlio, a densidade demogr\u00e1fica e a taxa de crescimento anual da popula\u00e7\u00e3o e dos domic\u00edlios.<!--more--><\/p>\n<p>A expectativa \u00e9 enorme por parte dos munic\u00edpios, principalmente porque h\u00e1 o risco real de redu\u00e7\u00e3o do n\u00famero de habitantes em diversas cidades como, por exemplo Cataguases, Leopoldina e Ub\u00e1, conforme uma pr\u00e9via divulgada pelo pr\u00f3prio IBGE e que causou alvoro\u00e7o entre os gestores municipais. O motivo \u00e9 simples: menos habitantes, menor o repasse de recursos do FPM &#8211; Fundo de Participa\u00e7\u00e3o dos Munic\u00edpios.<\/p>\n<p>Segundo este Site apurou, em Cataguases, \u00e9 esperada uma redu\u00e7\u00e3o da popula\u00e7\u00e3o, por\u00e9m, ela seria insuficiente para fazer com que o munic\u00edpio perca receita do FPM. O Censo \u00e9 como uma fotografia do pa\u00eds. A partir dos resultados \u00e9 poss\u00edvel tra\u00e7ar pol\u00edticas p\u00fablicas, com a\u00e7\u00f5es que beneficiam a todos. O \u00faltimo Censo foi realizado em 2010. Por fim, vale registrar que os recenseadores do IBGE enfrentaram dificuldades de toda ordem para entrevistar a popula\u00e7\u00e3o, desde as comunidades lideradas pelo narcotr\u00e1fico at\u00e9 com s\u00edndicos de condom\u00ednios de luxo.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2023\/01\/28\/prefeitura-de-leopoldina-e-ibge-fazem-mutirao-do-censo\/\"><strong><span style=\"color: #800000;\">Prefeitura de Leopoldina e IBGE fazem mutir\u00e3o do Censo<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2022\/11\/17\/ibge-tem-dificuldades-para-concluir-o-censo-2022\/\"><strong><span style=\"color: #800000;\">IBGE tem dificuldades para concluir o Censo 2022<\/span><\/strong><\/a><\/p>\n<p>Fonte: IBGE e Senado Federal | Foto: Helena Pontes &#8211; Ag. IBGE<\/p>\n<div class=\"kzlgu6a97ec0c5671a\" ><div style=\"margin-left: auto; margin-right: auto; text-align: center; margin-top: 50px; \" id=\"teste-2055882859\"><a href=\"https:\/\/marcelolopes.jor.br\/site\/edital-audiencia-publica-energisa-minas-rio-2026\/\" aria-label=\"banneredital\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png\" alt=\"\"  srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital.png 812w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-300x56.png 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/09\/banneredital-768x144.png 768w\" sizes=\"(max-width: 812px) 100vw, 812px\" width=\"812\" height=\"152\"  style=\"display: inline-block;\" \/><\/a><\/div><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.kzlgu6a97ec0c5671a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kzlgu6a97ec0c5671a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kzlgu6a97ec0c5671a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kzlgu6a97ec0c5671a {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kzlgu6a97ec0c5671a {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"izose6a97ec0c5d69d\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.izose6a97ec0c5d69d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.izose6a97ec0c5d69d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.izose6a97ec0c5d69d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.izose6a97ec0c5d69d {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.izose6a97ec0c5d69d {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>O IBGE vai divulgar, \u00e0s 10 horas de hoje, 28 de junho, os Primeiros Resultados de Popula\u00e7\u00e3o e Domic\u00edlios do Censo Demogr\u00e1fico 2022, apresentando um conjunto de informa\u00e7\u00f5es b\u00e1sicas sobre os totais populacionais e de domic\u00edlios no Pa\u00eds em diferentes<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/\">Leia mais <span class=\"screen-reader-text\">IBGE divulga hoje, 28, os primeiros resultados do Censo 2022<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":41853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-41852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IBGE divulga hoje, 28, os primeiros resultados do Censo 2022<\/title>\n<meta name=\"description\" content=\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022\" \/>\n<meta property=\"og:description\" content=\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-28T10:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022\",\"datePublished\":\"2023-06-28T10:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/1_77575-27211790-jpg.webp\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/\",\"name\":\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/1_77575-27211790-jpg.webp\",\"datePublished\":\"2023-06-28T10:00:30+00:00\",\"description\":\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/1_77575-27211790-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/1_77575-27211790-jpg.webp\",\"width\":675,\"height\":450,\"caption\":\"IBGE divulga hoje 28\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/06\\\/28\\\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-logo2026.png\",\"width\":328,\"height\":96,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022","description":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022","og_description":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2023-06-28T10:00:30+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022","datePublished":"2023-06-28T10:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/","url":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/","name":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp","datePublished":"2023-06-28T10:00:30+00:00","description":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022. Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/06\/1_77575-27211790-jpg.webp","width":675,"height":450,"caption":"IBGE divulga hoje 28"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/06\/28\/ibge-divulga-hoje-28-os-primeiros-resultados-do-censo-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"IBGE divulga hoje, 28, os primeiros resultados do Censo 2022"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2026\/07\/cropped-logo2026.png","width":328,"height":96,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Munic\u00edpios podem perder arrecada\u00e7\u00e3o se n\u00famero de habitantes diminuir.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/41852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=41852"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/41852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/41853"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=41852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=41852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=41852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}