{"id":39586,"date":"2023-02-24T07:00:43","date_gmt":"2023-02-24T10:00:43","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=39586"},"modified":"2024-07-02T14:29:45","modified_gmt":"2024-07-02T17:29:45","slug":"projeto-rio-pomba-valley-forma-e-contrata-profissionais","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/","title":{"rendered":"Projeto Rio Pomba Valley forma e contrata profissionais"},"content":{"rendered":"<p>\u00c9 em Cataguases, cidade cheia de hist\u00f3rias para contar, que o futuro brota com um hub de educa\u00e7\u00e3o digital e empreendedorismo chamado <a href=\"https:\/\/www.energisajuntos.com.br\/um-celeiro-high-tech-na-zona-da-mata-mineira\/\"><strong><span style=\"color: #800000;\">Rio Pomba Valley<\/span><\/strong><\/a>, projeto do grupo Energisa em parceria com SESI, SENAI, CNI e FIEMG, que oferece cursos na \u00e1rea de tecnologia da informa\u00e7\u00e3o. O objetivo \u00e9 oferecer novas oportunidades de crescimento e gera\u00e7\u00e3o de emprego de qualidade para a regi\u00e3o.<!--more--><\/p>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf8 Siga o Site do Marcelo Lopes no <a href=\"https:\/\/www.facebook.com\/sitedomarcelolopes\/\"><strong><span style=\"color: #800000;\">Facebook<\/span><\/strong><\/a> e no <strong><span style=\"color: #800000;\"><a style=\"color: #800000;\" href=\"https:\/\/www.instagram.com\/sitedomarcelolopes\/\">Instagram<\/a><\/span><\/strong><\/span><\/h4>\n<h4 class=\"p1\"><span class=\"s1\">\ud83d\udcf1Receba no <a href=\"https:\/\/chat.whatsapp.com\/BibzcI1ibYSKytbdyzubLA\"><strong><span style=\"color: #800000;\">WhatsApp<\/span><\/strong><\/a> as not\u00edcias do Site do Marcelo Lopes<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p>Em dezembro de 2022, foram formados 40 profissionais, divididos em desenvolvedores de front end (estrutura, design, conte\u00fado e desempenho) e de back end (servidor, banco de dados e aplica\u00e7\u00e3o).<\/p>\n<p>No \u00faltimo dia 16 de fevereiro, dez destes profissionais ingressaram na Energisa. Quando entrou no curso, J\u00e9ssica Campos estava se formando em administra\u00e7\u00e3o, mas trabalhava como estagi\u00e1ria na \u00e1rea de tecnologia da Energisa. \u201cO curso foi fundamental para a minha transi\u00e7\u00e3o para a \u00e1rea de tecnologia. A troca de conhecimentos, o aprendizado de um verdadeiro trabalho em equipe e as no\u00e7\u00f5es de diferentes linguagens de programa\u00e7\u00e3o foram experi\u00eancias \u00fanicas que me deram a oportunidade de conhecer e ingressar em uma nova \u00e1rea de trabalho. Uma iniciativa que tem muito potencial e que continue formando novos profissionais\u201d, conta ela que foi uma das contratadas.<\/p>\n<p>E n\u00e3o para por a\u00ed. A pr\u00f3xima etapa \u00e9 fomentar a empregabilidade junto \u00e0s empresas parceiras, como tamb\u00e9m realizar um processo seletivo para capta\u00e7\u00e3o de profissionais para \u00e1reas de inova\u00e7\u00e3o e tecnologia da informa\u00e7\u00e3o da empresa. At\u00e9 2026, est\u00e1 prevista a forma\u00e7\u00e3o de mais 510 novos profissionais. O objetivo \u00e9 fomentar a empregabilidade e empreendedorismo, criando um hub tecnol\u00f3gico e de inova\u00e7\u00e3o na Zona da Mata Mineira. Com isso, vai se formando em Cataguases um ambiente perfeito para o desenvolvimento tecnol\u00f3gico, retomando as tradi\u00e7\u00f5es inventivas da regi\u00e3o.<\/p>\n<p>A escolha pela Zona da Mata Mineira atende, ao mesmo tempo, a vis\u00e3o de futuro e a hist\u00f3ria centen\u00e1ria da empresa, que aqui nasceu. Integrante da regi\u00e3o, a cidade de Cataguases cresceu junto com a Energisa, considerado o maior grupo nacional privado do setor el\u00e9trico no Brasil. Mais de um s\u00e9culo depois, o Grupo Energisa aposta na sua estrat\u00e9gia de inova\u00e7\u00e3o para dar continuidade \u00e0 transforma\u00e7\u00e3o e ao avan\u00e7o da regi\u00e3o.<\/p>\n<figure id=\"attachment_39589\" aria-describedby=\"caption-attachment-39589\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39589\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image008-300x187.jpg\" alt=\"Projeto Rio Pomba Valley\" width=\"700\" height=\"437\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image008-300x187.jpg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image008.jpg 578w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-39589\" class=\"wp-caption-text\">Novos profissionais formados pelo Rio Pomba Valley e contratados pela Energisa.<\/figcaption><\/figure>\n<figure id=\"attachment_39588\" aria-describedby=\"caption-attachment-39588\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-39588\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image005-300x194.jpg\" alt=\"Projeto Rio Pomba Valley\" width=\"700\" height=\"453\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image005-300x194.jpg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image005.jpg 581w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-39588\" class=\"wp-caption-text\">Novos profissionais formados pelo Rio Pomba Valley e contratados pela Energisa.<\/figcaption><\/figure>\n<p><strong>LEIA TAMB\u00c9M<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2023\/01\/25\/energisa-vai-capacitar-550-jovens-ate-2026\/\"><strong><span style=\"color: #800000;\">Energisa vai capacitar 550 jovens at\u00e9 2026<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2022\/10\/10\/energisa-da-andamento-ao-programa-rio-pomba-valley\/\"><strong><span style=\"color: #800000;\">Energisa d\u00e1 andamento ao programa Rio Pomba Valley<\/span><\/strong><\/a><\/p>\n<p>Fonte e foto: Energisa<\/p>\n<div class=\"vivyx6a04389a500c6\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.vivyx6a04389a500c6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vivyx6a04389a500c6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vivyx6a04389a500c6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vivyx6a04389a500c6 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vivyx6a04389a500c6 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"kvbwr6a04389a54e11\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.kvbwr6a04389a54e11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.kvbwr6a04389a54e11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.kvbwr6a04389a54e11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.kvbwr6a04389a54e11 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.kvbwr6a04389a54e11 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 em Cataguases, cidade cheia de hist\u00f3rias para contar, que o futuro brota com um hub de educa\u00e7\u00e3o digital e empreendedorismo chamado Rio Pomba Valley, projeto do grupo Energisa em parceria com SESI, SENAI, CNI e FIEMG, que oferece cursos<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/\">Leia mais <span class=\"screen-reader-text\">Projeto Rio Pomba Valley forma e contrata profissionais<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":39587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto Rio Pomba Valley forma e contrata profissionais<\/title>\n<meta name=\"description\" content=\"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto Rio Pomba Valley forma e contrata profissionais\" \/>\n<meta property=\"og:description\" content=\"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-24T10:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T17:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Projeto Rio Pomba Valley forma e contrata profissionais\",\"datePublished\":\"2023-02-24T10:00:43+00:00\",\"dateModified\":\"2024-07-02T17:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/image002.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/\",\"name\":\"Projeto Rio Pomba Valley forma e contrata profissionais\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/image002.jpg\",\"datePublished\":\"2023-02-24T10:00:43+00:00\",\"dateModified\":\"2024-07-02T17:29:45+00:00\",\"description\":\"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/image002.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/image002.jpg\",\"width\":567,\"height\":272,\"caption\":\"Projeto Rio Pomba Valley\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/24\\\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto Rio Pomba Valley forma e contrata profissionais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto Rio Pomba Valley forma e contrata profissionais","description":"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto Rio Pomba Valley forma e contrata profissionais","og_description":"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2023-02-24T10:00:43+00:00","article_modified_time":"2024-07-02T17:29:45+00:00","og_image":[{"width":567,"height":272,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Projeto Rio Pomba Valley forma e contrata profissionais","datePublished":"2023-02-24T10:00:43+00:00","dateModified":"2024-07-02T17:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/","url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/","name":"Projeto Rio Pomba Valley forma e contrata profissionais","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg","datePublished":"2023-02-24T10:00:43+00:00","dateModified":"2024-07-02T17:29:45+00:00","description":"Projeto Rio Pomba Valley forma e contrata profissionais. At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/image002.jpg","width":567,"height":272,"caption":"Projeto Rio Pomba Valley"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/24\/projeto-rio-pomba-valley-forma-e-contrata-profissionais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Projeto Rio Pomba Valley forma e contrata profissionais"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"At\u00e9 2026, Energisa vai capacitar 550 jovens na \u00e1rea de programa\u00e7\u00e3o e de software.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=39586"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/39587"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=39586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=39586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=39586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}