{"id":39549,"date":"2023-02-21T13:00:50","date_gmt":"2023-02-21T16:00:50","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=39549"},"modified":"2023-02-21T11:24:24","modified_gmt":"2023-02-21T14:24:24","slug":"pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/","title":{"rendered":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre"},"content":{"rendered":"<p>A Pol\u00edcia Militar apreendeu uma certa quantidade de drogas no come\u00e7o da madrugada desta ter\u00e7a-feira, 21 de fevereiro, no Bairro Pouso Alegre. O fato foi registrado durante patrulhamento de rotina naquele bairro, conforme o registro policial.<!--more--><\/p>\n<p>De acordo com o boletim de ocorr\u00eancia a equipe policial que fazia patrulhamento pela rua Edson Fabrino Bai\u00e3o, no Bairro Pouso Alegre, viu um jovem de 18 anos, conhecido no meio policial por envolvimento com o tr\u00e1fico de drogas, na cal\u00e7ada em frente a uma boca de fumo.<\/p>\n<p>Ao ver os militares o rapaz saiu correndo sem fechar o port\u00e3o do im\u00f3vel. Os militares entraram no local e na garagem encontraram uma sacola com 82 pedras de crack e 3 buchas de maconha que foram apreendidas. Mesmo com um rastreamento feito pelos policiais, o jovem n\u00e3o foi localizado.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2022\/12\/29\/pm-apreende-drogas-no-pouso-alegre-e-prende-cinco-por-trafico\/\"><strong><span style=\"color: #800000;\">PM apreende drogas no Pouso Alegre e prende cinco por tr\u00e1fico<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2022\/01\/04\/jovem-e-preso-no-pouso-alegre-com-tres-pedras-brutas-de-crack-na-cueca\/\"><strong><span style=\"color: #800000;\">Jovem \u00e9 preso no Pouso Alegre com tr\u00eas pedras brutas de crack na cueca<\/span><\/strong><\/a><\/p>\n<p>Foto: Pol\u00edcia Militar-divulga\u00e7\u00e3o<\/p>\n<div class=\"rjngy6a03d8c0e14de\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.rjngy6a03d8c0e14de {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.rjngy6a03d8c0e14de {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.rjngy6a03d8c0e14de {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.rjngy6a03d8c0e14de {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.rjngy6a03d8c0e14de {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"dtvov6a03d8c0e7652\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.dtvov6a03d8c0e7652 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.dtvov6a03d8c0e7652 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.dtvov6a03d8c0e7652 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.dtvov6a03d8c0e7652 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.dtvov6a03d8c0e7652 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar apreendeu uma certa quantidade de drogas no come\u00e7o da madrugada desta ter\u00e7a-feira, 21 de fevereiro, no Bairro Pouso Alegre. O fato foi registrado durante patrulhamento de rotina naquele bairro, conforme o registro policial.<\/p>\n","protected":false},"author":2,"featured_media":39550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PM apreende drogas em boca de fumo no Bairro Pouso Alegre<\/title>\n<meta name=\"description\" content=\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre\" \/>\n<meta property=\"og:description\" content=\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T16:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre\",\"datePublished\":\"2023-02-21T16:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/\"},\"wordCount\":185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/boca-de-fumo.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/\",\"name\":\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/boca-de-fumo.jpg\",\"datePublished\":\"2023-02-21T16:00:50+00:00\",\"description\":\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/boca-de-fumo.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/boca-de-fumo.jpg\",\"width\":800,\"height\":537,\"caption\":\"PM apreende drogas em\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/21\\\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PM apreende drogas em boca de fumo no Bairro Pouso Alegre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre","description":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/","og_locale":"pt_BR","og_type":"article","og_title":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre","og_description":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2023-02-21T16:00:50+00:00","og_image":[{"width":800,"height":537,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre","datePublished":"2023-02-21T16:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/"},"wordCount":185,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/","url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/","name":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg","datePublished":"2023-02-21T16:00:50+00:00","description":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre. O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/boca-de-fumo.jpg","width":800,"height":537,"caption":"PM apreende drogas em"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/21\/pm-apreende-drogas-em-boca-de-fumo-no-bairro-pouso-alegre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"PM apreende drogas em boca de fumo no Bairro Pouso Alegre"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"O jovem de 18 anos que estava no local conseguiu fugir, mas foi identificado.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=39549"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/39550"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=39549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=39549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=39549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}