{"id":39490,"date":"2023-02-18T11:00:24","date_gmt":"2023-02-18T14:00:24","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=39490"},"modified":"2023-02-18T11:00:33","modified_gmt":"2023-02-18T14:00:33","slug":"alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/","title":{"rendered":"Alegria e muitos shows marcam os primeiros dias de Carnaval"},"content":{"rendered":"<p>E o cataguasense voltou a curtir o carnaval como gosta. A folia come\u00e7ou oficialmente na quarta-feira, 15, com o Bloco Pipoca, do vereador Ricardo Dias. Ele levou para a Avenida um trio el\u00e9trico e v\u00e1rias atra\u00e7\u00f5es. Enquanto a chuva n\u00e3o caiu, a alegria tomou conta do grande p\u00fablico que estava no local e foi animado pelo DJ Pedro Cond\u00e9. Tamb\u00e9m estavam previstos para se apresentar Tiago Borges, Jana\u00edna Gentil e Nayara Aleixo.<!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39492\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n-300x200.jpg\" alt=\"Alegria e muitos shows\" width=\"700\" height=\"467\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n-300x200.jpg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n-1024x683.jpg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n-768x512.jpg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n-1200x800.jpg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/332119587_1226397358280808_708516052901850835_n.jpg 1440w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>A noite de quinta-feira, 16 de fevereiro, foi de festa e alegria no Carnaval de Cataguases. As atra\u00e7\u00f5es culminaram com o excelente show da Banda Exigeotom no palco montado na Avenida Astolfo Dutra. O grupo cataguasense de samba e pagode, mais uma vez arrebatou o p\u00fablico com um excelente repert\u00f3rio e fez um show que, literalmente, ajudou a matar a saudade que o p\u00fablico estava do carnaval.<\/p>\n<p>Da avenida para o <a href=\"http:\/\/www.cluberemo.com.br\"><strong><span style=\"color: #800000;\">Clube<\/span><\/strong><\/a> onde o Bloco do Remo, que ficou n\u00e3o saiu \u00e0s ruas, permanecendo na quadra do Clube, teve \u00e0 frente a bateria do Bloco Rebenta e apresenta\u00e7\u00e3o do grupo Sambarilove. Um tremendo sucesso, como acontece todos os anos. O Remo ainda prestou homenagens a pessoas que contribu\u00edram para o Carnaval de Cataguases, como Chico Salgado, Chic\u00e3o (\u201cBloco do Eu Sozinho\u201d), Elisa Nunes, Luiz Boneca e Mimi Carrara.<\/p>\n<p>Nesta sexta-feira, 17, os blocos do Bar do Adilson, Unidos Sem Preconceitos e Rebenta tomaram as ruas da cidade numa s\u00f3 alegria. Logo depois foi a vez da Banda Salamandra fazer sua apresenta\u00e7\u00e3o no palco da Avenida Astolfo Dutra. Uma das mais concorridas da regi\u00e3o, a Salamandra mostrou mais uma vez a que veio e fez o p\u00fablico tirar o p\u00e9 do ch\u00e3o e dan\u00e7ar muito com um repert\u00f3rio com muito ax\u00e9 e outros ritmos de sucesso, coroando de alegria mais uma noite de carnaval.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-39493\" src=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande-300x169.jpeg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande-300x169.jpeg 300w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande-1024x576.jpeg 1024w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande-768x432.jpeg 768w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande-1200x675.jpeg 1200w, https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/IMG_8396-Grande.jpeg 1280w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3>Aten\u00e7\u00e3o para a preven\u00e7\u00e3o<\/h3>\n<p>Durante o per\u00edodo carnavalesco, a Secretaria de Sa\u00fade, por meio da Vigil\u00e2ncia Epidemiol\u00f3gica, est\u00e1 distribuindo kit\u2019s preventivos contra S\u00edfilis e HIV. Conforme a coordenadora do setor, Tairises Roque, a campanha tem o objetivo de alertar os foli\u00f5es para a import\u00e2ncia do sexo seguro, \u201ce isso vale n\u00e3o s\u00f3 no carnaval como tamb\u00e9m o ano todo\u201d, ressalta, alertando que os \u00edndices epidemiol\u00f3gicos relativos \u00e0s IST\u2019s (infec\u00e7\u00f5es sexualmente transmiss\u00edveis) est\u00e3o elevados no munic\u00edpio, o que demanda ainda mais cuidado e preven\u00e7\u00e3o.<\/p>\n<p><strong>LEIA TAMB\u00c9M<\/strong><br \/>\n<a href=\"https:\/\/marcelolopes.jor.br\/2023\/02\/16\/baluartes-do-samba-retornam-a-praca-rui-barbosa-neste-sabado-de-carnaval\/\"><strong><span style=\"color: #800000;\">Baluartes do Samba retornam \u00e0 Pra\u00e7a Rui Barbosa neste s\u00e1bado de carnaval<\/span><\/strong><\/a><\/p>\n<p><a href=\"https:\/\/marcelolopes.jor.br\/2023\/02\/05\/prefeitura-divulga-programacao-de-carnaval-em-cataguases\/\"><strong><span style=\"color: #800000;\">Prefeitura divulga programa\u00e7\u00e3o de Carnaval em Cataguases<\/span><\/strong><\/a><\/p>\n<p>Foto: LP Produ\u00e7\u00f5es e informa\u00e7\u00f5es da Prefeitura de Cataguases<\/p>\n<div class=\"tcegv6a03d4cc2d356\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.tcegv6a03d4cc2d356 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.tcegv6a03d4cc2d356 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.tcegv6a03d4cc2d356 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.tcegv6a03d4cc2d356 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.tcegv6a03d4cc2d356 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"gkfdp6a03d4cc34850\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.gkfdp6a03d4cc34850 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.gkfdp6a03d4cc34850 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.gkfdp6a03d4cc34850 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.gkfdp6a03d4cc34850 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.gkfdp6a03d4cc34850 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>E o cataguasense voltou a curtir o carnaval como gosta. A folia come\u00e7ou oficialmente na quarta-feira, 15, com o Bloco Pipoca, do vereador Ricardo Dias. Ele levou para a Avenida um trio el\u00e9trico e v\u00e1rias atra\u00e7\u00f5es. Enquanto a chuva n\u00e3o<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/\">Leia mais <span class=\"screen-reader-text\">Alegria e muitos shows marcam os primeiros dias de Carnaval<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":39491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alegria e muitos shows marcam os primeiros dias de carnaval<\/title>\n<meta name=\"description\" content=\"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alegria e muitos shows marcam os primeiros dias de carnaval\" \/>\n<meta property=\"og:description\" content=\"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-18T14:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-18T14:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"Alegria e muitos shows marcam os primeiros dias de Carnaval\",\"datePublished\":\"2023-02-18T14:00:24+00:00\",\"dateModified\":\"2023-02-18T14:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/331526085_5887359081379352_3797372879492507693_n.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/\",\"name\":\"Alegria e muitos shows marcam os primeiros dias de carnaval\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/331526085_5887359081379352_3797372879492507693_n.jpg\",\"datePublished\":\"2023-02-18T14:00:24+00:00\",\"dateModified\":\"2023-02-18T14:00:33+00:00\",\"description\":\"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/331526085_5887359081379352_3797372879492507693_n.jpg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/331526085_5887359081379352_3797372879492507693_n.jpg\",\"width\":1440,\"height\":960,\"caption\":\"Alegria e muitos shows\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2023\\\/02\\\/18\\\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alegria e muitos shows marcam os primeiros dias de Carnaval\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alegria e muitos shows marcam os primeiros dias de carnaval","description":"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/","og_locale":"pt_BR","og_type":"article","og_title":"Alegria e muitos shows marcam os primeiros dias de carnaval","og_description":"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2023-02-18T14:00:24+00:00","article_modified_time":"2023-02-18T14:00:33+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"Alegria e muitos shows marcam os primeiros dias de Carnaval","datePublished":"2023-02-18T14:00:24+00:00","dateModified":"2023-02-18T14:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/","url":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/","name":"Alegria e muitos shows marcam os primeiros dias de carnaval","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg","datePublished":"2023-02-18T14:00:24+00:00","dateModified":"2023-02-18T14:00:33+00:00","description":"Alegria e muitos shows marcam os primeiros dias de carnaval. Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2023\/02\/331526085_5887359081379352_3797372879492507693_n.jpg","width":1440,"height":960,"caption":"Alegria e muitos shows"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2023\/02\/18\/alegria-e-muitos-shows-marcam-os-primeiros-dias-de-carnaval\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"Alegria e muitos shows marcam os primeiros dias de Carnaval"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Programa\u00e7\u00e3o diversificada leva grande p\u00fablico para a Avenida.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=39490"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/39490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/39491"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=39490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=39490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=39490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}