{"id":37028,"date":"2022-11-01T16:00:30","date_gmt":"2022-11-01T19:00:30","guid":{"rendered":"https:\/\/marcelolopes.jor.br\/?p=37028"},"modified":"2022-11-07T11:27:55","modified_gmt":"2022-11-07T14:27:55","slug":"br-116-em-muriae-segue-bloqueada-por-manifestantes","status":"publish","type":"post","link":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/","title":{"rendered":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes"},"content":{"rendered":"<p>Mesmo com a determina\u00e7\u00e3o judicial para liberar rodovias federais bloqueadas por bolsonaristas que protestam contra os resultados das urnas na elei\u00e7\u00e3o para presidente, o movimento persiste. Em Muria\u00e9, por exemplo, no come\u00e7o da tarde desta ter\u00e7a-feira, 1\u00ba de novembro, centenas de caminh\u00f5es permanecem parados na regi\u00e3o do Bela Vista, conforme informou o Site Silvan Alves.<!--more--><\/p>\n<p>No come\u00e7o da manh\u00e3 de hoje, haviam pontos de lentid\u00e3o de tr\u00e1fego na rodovia entre Ub\u00e1 e Tocantins. Os atos tiveram in\u00edcio ap\u00f3s os resultados do 2\u00ba turno das elei\u00e7\u00f5es que terminou com a derrota de Jair Bolsonaro (PL) e vit\u00f3ria de Luiz In\u00e1cio Lula da Silva (PT). Na segunda-feira, pelo menos 23 estados e o Distrito Federal registraram mais de 300 estradas fechadas.<\/p>\n<p>O governador reeleito de Minas Gerais Romeu Zema (Novo), que apoiou Bolsonaro no segundo turno, disse, nesta ter\u00e7a-feira, em uma rede social, que \u00e9 preciso garantir o direito de ir e vir das pessoas e impedir que haja desabastecimento de alimentos e outros produtos. Ele solicitou \u00e0s for\u00e7as de seguran\u00e7a estaduais que conduzam a desobstru\u00e7\u00e3o de estradas no Estado, que est\u00e3o total ou parcialmente fechadas por apoiadores de Jair Bolsonaro (PL) que n\u00e3o aceitam a derrota do presidente nas urnas.<\/p>\n<p>A Pol\u00edcia Rodovi\u00e1ria Federal (PRF) afirmou, em coletiva de imprensa nesta ter\u00e7a-feira, que n\u00e3o est\u00e1 se omitindo e que trabalha para desbloquear as rodovias brasileiras \u201co quanto antes\u201d, por\u00e9m n\u00e3o deu prazo para conseguir dispersar os manifestantes. \u201cN\u00e3o conseguimos falar em qual hor\u00e1rio ou dia vai ser [a libera\u00e7\u00e3o total]. Estamos empregando todos os esfor\u00e7os\u201d, pontuou o diretor executivo da corpora\u00e7\u00e3o, Marco Ant\u00f4nio Territo de Barros.<\/p>\n<p>Fonte: Site Silvan Alves e Jornal O Tempo | Foto a\u00e9rea: Jo\u00e3o Guilherme e Elias Souza<\/p>\n<div class=\"icbwn6a03d5091b20c\" ><br><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.icbwn6a03d5091b20c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.icbwn6a03d5091b20c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.icbwn6a03d5091b20c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.icbwn6a03d5091b20c {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.icbwn6a03d5091b20c {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n<div class=\"vripz6a03d50921873\" ><div id=\"div_destino\"><\/div>\r\n<script src=\"https:\/\/cdn.snsrsv.com\/sdk.js\"><\/script>\r\n<script >\r\n      new sdk(\"464030C30061EA8BE065000000000001\") \r\n          .appendTo(\"div_destino\")\r\n          .disableStyle(true) \r\n          .setCacheBusterMacro(\"%%CACHEBUSTER%%\")\r\n          .setSize(\"800\",\"214\")\r\n          .setClickMacro(\"%%CLICK_URL_ESC%%\") \r\n          .setReferrerUrlMacro(\"%%REFERRER_URL_ESC%%\") \r\n          .start(); \r\n<\/script><\/div><style type=\"text\/css\">\r\n@media screen and (min-width: 1201px) {\r\n.vripz6a03d50921873 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 993px) and (max-width: 1200px) {\r\n.vripz6a03d50921873 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 769px) and (max-width: 992px) {\r\n.vripz6a03d50921873 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (min-width: 768px) and (max-width: 768px) {\r\n.vripz6a03d50921873 {\r\ndisplay: block;\r\n}\r\n}\r\n@media screen and (max-width: 767px) {\r\n.vripz6a03d50921873 {\r\ndisplay: block;\r\n}\r\n}\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"<p>Mesmo com a determina\u00e7\u00e3o judicial para liberar rodovias federais bloqueadas por bolsonaristas que protestam contra os resultados das urnas na elei\u00e7\u00e3o para presidente, o movimento persiste. Em Muria\u00e9, por exemplo, no come\u00e7o da tarde desta ter\u00e7a-feira, 1\u00ba de novembro, centenas<\/p>\n<p class=\"link-more\"><a class=\"more-link\" href=\"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/\">Leia mais <span class=\"screen-reader-text\">BR-116 em Muria\u00e9 segue bloqueada por manifestantes<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":37029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","thumb-below-title"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BR-116 em Muria\u00e9 segue bloqueada por manifestantes<\/title>\n<meta name=\"description\" content=\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes\" \/>\n<meta property=\"og:description\" content=\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Marcelo Lopes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sitedomarcelolopes\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-01T19:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-07T14:27:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"398\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcelo Lopes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcelo Lopes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/\"},\"author\":{\"name\":\"Marcelo Lopes\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\"},\"headline\":\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes\",\"datePublished\":\"2022-11-01T19:00:30+00:00\",\"dateModified\":\"2022-11-07T14:27:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/\",\"name\":\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg\",\"datePublished\":\"2022-11-01T19:00:30+00:00\",\"dateModified\":\"2022-11-07T14:27:55+00:00\",\"description\":\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg\",\"width\":707,\"height\":398,\"caption\":\"BR-116 em Muria\u00e9 segue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/2022\\\/11\\\/01\\\/br-116-em-muriae-segue-bloqueada-por-manifestantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BR-116 em Muria\u00e9 segue bloqueada por manifestantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"name\":\"Marcelo Lopes\",\"description\":\"Not\u00edcias de Cataguases e Regi\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#organization\",\"name\":\"Site do Marcelo Lopes\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-1.png\",\"width\":475,\"height\":80,\"caption\":\"Site do Marcelo Lopes\"},\"image\":{\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sitedomarcelolopes\",\"https:\\\/\\\/www.instagram.com\\\/sitedomarcelolopes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/site-do-marcelo-lopes\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/marcelolopes957\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/#\\\/schema\\\/person\\\/3e7216a35c34d8fdf952b31da3d1f89f\",\"name\":\"Marcelo Lopes\",\"sameAs\":[\"http:\\\/\\\/www.marcelolopes.jor.br\"],\"url\":\"https:\\\/\\\/marcelolopes.jor.br\\\/site\\\/author\\\/marcelo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes","description":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/","og_locale":"pt_BR","og_type":"article","og_title":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes","og_description":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.","og_url":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/","og_site_name":"Marcelo Lopes","article_publisher":"https:\/\/www.facebook.com\/sitedomarcelolopes","article_published_time":"2022-11-01T19:00:30+00:00","article_modified_time":"2022-11-07T14:27:55+00:00","og_image":[{"width":707,"height":398,"url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg","type":"image\/jpeg"}],"author":"Marcelo Lopes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marcelo Lopes","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#article","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/"},"author":{"name":"Marcelo Lopes","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f"},"headline":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes","datePublished":"2022-11-01T19:00:30+00:00","dateModified":"2022-11-07T14:27:55+00:00","mainEntityOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/","url":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/","name":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes","isPartOf":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#primaryimage"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#primaryimage"},"thumbnailUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg","datePublished":"2022-11-01T19:00:30+00:00","dateModified":"2022-11-07T14:27:55+00:00","description":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes. Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.","breadcrumb":{"@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#primaryimage","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2022\/11\/WhatsApp-Image-2022-11-01-at-12.17.13_707x398.jpeg","width":707,"height":398,"caption":"BR-116 em Muria\u00e9 segue"},{"@type":"BreadcrumbList","@id":"https:\/\/marcelolopes.jor.br\/site\/2022\/11\/01\/br-116-em-muriae-segue-bloqueada-por-manifestantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/marcelolopes.jor.br\/site\/"},{"@type":"ListItem","position":2,"name":"BR-116 em Muria\u00e9 segue bloqueada por manifestantes"}]},{"@type":"WebSite","@id":"https:\/\/marcelolopes.jor.br\/site\/#website","url":"https:\/\/marcelolopes.jor.br\/site\/","name":"Marcelo Lopes","description":"Not\u00edcias de Cataguases e Regi\u00e3o","publisher":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcelolopes.jor.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/marcelolopes.jor.br\/site\/#organization","name":"Site do Marcelo Lopes","url":"https:\/\/marcelolopes.jor.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","contentUrl":"https:\/\/marcelolopes.jor.br\/site\/wp-content\/uploads\/2024\/11\/logo-1.png","width":475,"height":80,"caption":"Site do Marcelo Lopes"},"image":{"@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sitedomarcelolopes","https:\/\/www.instagram.com\/sitedomarcelolopes\/","https:\/\/www.linkedin.com\/company\/site-do-marcelo-lopes\/","https:\/\/www.youtube.com\/user\/marcelolopes957"]},{"@type":"Person","@id":"https:\/\/marcelolopes.jor.br\/site\/#\/schema\/person\/3e7216a35c34d8fdf952b31da3d1f89f","name":"Marcelo Lopes","sameAs":["http:\/\/www.marcelolopes.jor.br"],"url":"https:\/\/marcelolopes.jor.br\/site\/author\/marcelo\/"}]}},"wps_subtitle":"Em coletiva, PRF diz n\u00e3o poder prever a libera\u00e7\u00e3o das estradas.","_links":{"self":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/37028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/comments?post=37028"}],"version-history":[{"count":0,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/posts\/37028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media\/37029"}],"wp:attachment":[{"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/media?parent=37028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/categories?post=37028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcelolopes.jor.br\/site\/wp-json\/wp\/v2\/tags?post=37028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}